{"id":25592,"date":"2016-10-14T08:38:13","date_gmt":"2016-10-14T06:38:13","guid":{"rendered":"https:\/\/www.hgg-group.com\/knowledge\/verbindung-von-shipconstructor-mit-einer-3d-profiliermaschine\/"},"modified":"2024-09-19T12:54:16","modified_gmt":"2024-09-19T12:54:16","slug":"verbindung-von-shipconstructor-mit-einer-3d-profiliermaschine","status":"publish","type":"knowledge","link":"https:\/\/www.hgg-group.com\/de\/erkenntnis\/verbindung-von-shipconstructor-mit-einer-3d-profiliermaschine\/","title":{"rendered":"Verbindung von ShipConstructor mit einer 3D-Profiliermaschine"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"25592\" class=\"elementor elementor-25592 elementor-4932\" data-elementor-post-type=\"knowledge\">\n\t\t\t\t<div class=\"elementor-element elementor-element-457ab50 e-flex e-con-boxed e-con e-parent\" data-id=\"457ab50\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d31885c elementor-widget elementor-widget-text-editor\" data-id=\"d31885c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Wie holen Sie das Beste aus ShipConstructor und Ihrem HGG-Rechner heraus?<\/h3>\n<p>Ein CAD-Modell enth\u00e4lt eine Vielzahl von Daten \u00fcber die zu schneidenden Teile.<br \/>\nTraditionell w\u00fcrden die Menschen all diese Daten erneut programmieren, um die Teile zu schneiden.<br \/>\nDies ist ein sehr zeitaufw\u00e4ndiger und unn\u00f6tiger Prozess.<br \/>\nDank einer erfolgreichen Integration kann ShipConstructor einfach an eine <a href=\"https:\/\/www.hgg-group.com\/machine\/pcl-600\/\">HGG-Profilschneidanlage<\/a> angeschlossen werden.   <\/p>\n<h5>Detaillierung<\/h5>\n<p>SSI ShipConstructor enth\u00e4lt einen Katalog mit vordefinierten Endschnitten, Aussparungen und Durchdringungen.<br \/>\nDiese Werkzeuge k\u00f6nnen definiert und angewendet werden, um den Detaillierungsprozess zu beschleunigen.<br \/>\nAlle Teile m\u00fcssen einschlie\u00dflich der Markierungen detailliert werden, um eine vollst\u00e4ndige Extraktion der Konstruktionsdaten zu gew\u00e4hrleisten.  <\/p>\n<h5>Daten exportieren<\/h5>\n<p>Eine der Funktionen von SSI Enterprise-Platform PubliserLT ist die Extraktion von Konstruktionsdaten aus dem ShipConstructor-Modell. PublisherLT kann Teile als angereicherte .dxf-Dateien exportieren, die alle f\u00fcr die 3D-Profilierung erforderlichen Daten enthalten. Der Export umfasst Daten und Geometrie sowohl des Teils als auch der Markierungen. HGG&#8217;s ProCAD wird mit einem Hardwareschl\u00fcssel geliefert, der den Import und die Konvertierung dieser speziellen .dxf-Dateien durch ProCAM Framework zur weiteren Verarbeitung erm\u00f6glicht.<\/p>\n<p>Die Integration zwischen SSI ShipConstructor und HGG unterst\u00fctzt die Extraktion und Bearbeitung von Entwurfsdaten einschlie\u00dflich der Schr\u00e4gen.<\/p>\n<h5>Unterst\u00fctzte Profile<\/h5>\n<ul>\n<li>Abschl\u00e4ge<\/li>\n<li>Gl\u00fchbirnen<\/li>\n<li>Wohnungen<\/li>\n<li>Winkel<\/li>\n<\/ul>\n<p>Der Import von anderen Profilen mit<a href=\"https:\/\/www.hgg-group.com\/de\/procam\/\"> HGGs ProCAM<\/a> Framework wie H-, I- und U-Tr\u00e4gern ist auf Anfrage m\u00f6glich.<\/p>\n<h5>Geometrie der Teile<\/h5>\n<ul>\n<li>&#8218;Endschnitte&#8216; von Teileenden.<\/li>\n<li>&#8218;Ausschnitte&#8216; im Netz eines Profils f\u00fcr kreuzende Profile.<\/li>\n<li>Durchdringungen&#8220; wie L\u00f6cher in Rohrleitungen.<\/li>\n<li>Trimm-Winkel&#8216; f\u00fcr einfache Teile-Detaillierungen durch geradlinige Schnitte.<\/li>\n<\/ul>\n<h5>Geometrie markieren<\/h5>\n<ul>\n<li>Umgekehrte Biegelinien&#8220; f\u00fcr einfaches und genaues Biegen der Zwiebeln;<\/li>\n<li>Referenzmarkierung&#8220; f\u00fcr eine einfache und genaue Montage der Teile;<\/li>\n<li>&#8218;Teile-IDs&#8216; des Teils selbst oder die ID eines Verbindungsteils.<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Benutzen Sie ShipConstructor?<br \/>\nHolen Sie das Beste aus Ihrer HGG-Maschine heraus, indem Sie ShipConstructor mit Ihrem 3D Profiler verbinden. <\/p>\n","protected":false},"featured_media":4936,"template":"","knowledge-tag":[381],"class_list":["post-25592","knowledge","type-knowledge","status-publish","has-post-thumbnail","hentry","knowledge-tag-design-detailing-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Verbindung von ShipConstructor mit einer 3D-Profiliermaschine - HGG Group We Revolutionize The World Of Steel<\/title>\n<meta name=\"description\" content=\"Wie holen Sie das Beste aus ShipConstructor und Ihrem HGG-Rechner heraus? Vermeiden Sie zus\u00e4tzliche Programmierzeit. Lesen Sie, wie Sie Ihre Daten an Ihre Profiliermaschine exportieren k\u00f6nnen\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hgg-group.com\/de\/erkenntnis\/verbindung-von-shipconstructor-mit-einer-3d-profiliermaschine\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verbindung von ShipConstructor mit einer 3D-Profiliermaschine - HGG Group We Revolutionize The World Of Steel\" \/>\n<meta property=\"og:description\" content=\"Wie holen Sie das Beste aus ShipConstructor und Ihrem HGG-Rechner heraus? Vermeiden Sie zus\u00e4tzliche Programmierzeit. Lesen Sie, wie Sie Ihre Daten an Ihre Profiliermaschine exportieren k\u00f6nnen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hgg-group.com\/de\/erkenntnis\/verbindung-von-shipconstructor-mit-einer-3d-profiliermaschine\/\" \/>\n<meta property=\"og:site_name\" content=\"HGG Group\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-19T12:54:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hgg-group.com\/wp-content\/uploads\/2024\/04\/Shipconstructor_banner-1920x530-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hgg-group.com\\\/de\\\/erkenntnis\\\/verbindung-von-shipconstructor-mit-einer-3d-profiliermaschine\\\/\",\"url\":\"https:\\\/\\\/www.hgg-group.com\\\/de\\\/erkenntnis\\\/verbindung-von-shipconstructor-mit-einer-3d-profiliermaschine\\\/\",\"name\":\"Verbindung von ShipConstructor mit einer 3D-Profiliermaschine - HGG Group We Revolutionize The World Of Steel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hgg-group.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hgg-group.com\\\/de\\\/erkenntnis\\\/verbindung-von-shipconstructor-mit-einer-3d-profiliermaschine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hgg-group.com\\\/de\\\/erkenntnis\\\/verbindung-von-shipconstructor-mit-einer-3d-profiliermaschine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hgg-group.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Shipconstructor_banner-1920x530-1.jpg\",\"datePublished\":\"2016-10-14T06:38:13+00:00\",\"dateModified\":\"2024-09-19T12:54:16+00:00\",\"description\":\"Wie holen Sie das Beste aus ShipConstructor und Ihrem HGG-Rechner heraus? Vermeiden Sie zus\u00e4tzliche Programmierzeit. Lesen Sie, wie Sie Ihre Daten an Ihre Profiliermaschine exportieren k\u00f6nnen\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hgg-group.com\\\/de\\\/erkenntnis\\\/verbindung-von-shipconstructor-mit-einer-3d-profiliermaschine\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hgg-group.com\\\/de\\\/erkenntnis\\\/verbindung-von-shipconstructor-mit-einer-3d-profiliermaschine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.hgg-group.com\\\/de\\\/erkenntnis\\\/verbindung-von-shipconstructor-mit-einer-3d-profiliermaschine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hgg-group.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Shipconstructor_banner-1920x530-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hgg-group.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Shipconstructor_banner-1920x530-1.jpg\",\"width\":1920,\"height\":530},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hgg-group.com\\\/de\\\/erkenntnis\\\/verbindung-von-shipconstructor-mit-einer-3d-profiliermaschine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hgg-group.com\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wissen\",\"item\":\"https:\\\/\\\/www.hgg-group.com\\\/de\\\/erkenntnis\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Verbindung von ShipConstructor mit einer 3D-Profiliermaschine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hgg-group.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.hgg-group.com\\\/de\\\/\",\"name\":\"HGG Group\",\"description\":\"We Revolutionize The World Of Steel\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hgg-group.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hgg-group.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hgg-group.com\\\/de\\\/#organization\",\"name\":\"HGG\",\"url\":\"https:\\\/\\\/www.hgg-group.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.hgg-group.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hgg-group.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/HGG_logo-primair_RGB.png\",\"contentUrl\":\"https:\\\/\\\/www.hgg-group.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/HGG_logo-primair_RGB.png\",\"width\":1097,\"height\":1337,\"caption\":\"HGG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hgg-group.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verbindung von ShipConstructor mit einer 3D-Profiliermaschine - HGG Group We Revolutionize The World Of Steel","description":"Wie holen Sie das Beste aus ShipConstructor und Ihrem HGG-Rechner heraus? Vermeiden Sie zus\u00e4tzliche Programmierzeit. Lesen Sie, wie Sie Ihre Daten an Ihre Profiliermaschine exportieren k\u00f6nnen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hgg-group.com\/de\/erkenntnis\/verbindung-von-shipconstructor-mit-einer-3d-profiliermaschine\/","og_locale":"de_DE","og_type":"article","og_title":"Verbindung von ShipConstructor mit einer 3D-Profiliermaschine - HGG Group We Revolutionize The World Of Steel","og_description":"Wie holen Sie das Beste aus ShipConstructor und Ihrem HGG-Rechner heraus? Vermeiden Sie zus\u00e4tzliche Programmierzeit. Lesen Sie, wie Sie Ihre Daten an Ihre Profiliermaschine exportieren k\u00f6nnen","og_url":"https:\/\/www.hgg-group.com\/de\/erkenntnis\/verbindung-von-shipconstructor-mit-einer-3d-profiliermaschine\/","og_site_name":"HGG Group","article_modified_time":"2024-09-19T12:54:16+00:00","og_image":[{"width":1920,"height":530,"url":"https:\/\/www.hgg-group.com\/wp-content\/uploads\/2024\/04\/Shipconstructor_banner-1920x530-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hgg-group.com\/de\/erkenntnis\/verbindung-von-shipconstructor-mit-einer-3d-profiliermaschine\/","url":"https:\/\/www.hgg-group.com\/de\/erkenntnis\/verbindung-von-shipconstructor-mit-einer-3d-profiliermaschine\/","name":"Verbindung von ShipConstructor mit einer 3D-Profiliermaschine - HGG Group We Revolutionize The World Of Steel","isPartOf":{"@id":"https:\/\/www.hgg-group.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hgg-group.com\/de\/erkenntnis\/verbindung-von-shipconstructor-mit-einer-3d-profiliermaschine\/#primaryimage"},"image":{"@id":"https:\/\/www.hgg-group.com\/de\/erkenntnis\/verbindung-von-shipconstructor-mit-einer-3d-profiliermaschine\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hgg-group.com\/wp-content\/uploads\/2024\/04\/Shipconstructor_banner-1920x530-1.jpg","datePublished":"2016-10-14T06:38:13+00:00","dateModified":"2024-09-19T12:54:16+00:00","description":"Wie holen Sie das Beste aus ShipConstructor und Ihrem HGG-Rechner heraus? Vermeiden Sie zus\u00e4tzliche Programmierzeit. Lesen Sie, wie Sie Ihre Daten an Ihre Profiliermaschine exportieren k\u00f6nnen","breadcrumb":{"@id":"https:\/\/www.hgg-group.com\/de\/erkenntnis\/verbindung-von-shipconstructor-mit-einer-3d-profiliermaschine\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hgg-group.com\/de\/erkenntnis\/verbindung-von-shipconstructor-mit-einer-3d-profiliermaschine\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.hgg-group.com\/de\/erkenntnis\/verbindung-von-shipconstructor-mit-einer-3d-profiliermaschine\/#primaryimage","url":"https:\/\/www.hgg-group.com\/wp-content\/uploads\/2024\/04\/Shipconstructor_banner-1920x530-1.jpg","contentUrl":"https:\/\/www.hgg-group.com\/wp-content\/uploads\/2024\/04\/Shipconstructor_banner-1920x530-1.jpg","width":1920,"height":530},{"@type":"BreadcrumbList","@id":"https:\/\/www.hgg-group.com\/de\/erkenntnis\/verbindung-von-shipconstructor-mit-einer-3d-profiliermaschine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hgg-group.com\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Wissen","item":"https:\/\/www.hgg-group.com\/de\/erkenntnis\/"},{"@type":"ListItem","position":3,"name":"Verbindung von ShipConstructor mit einer 3D-Profiliermaschine"}]},{"@type":"WebSite","@id":"https:\/\/www.hgg-group.com\/de\/#website","url":"https:\/\/www.hgg-group.com\/de\/","name":"HGG Group","description":"We Revolutionize The World Of Steel","publisher":{"@id":"https:\/\/www.hgg-group.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hgg-group.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.hgg-group.com\/de\/#organization","name":"HGG","url":"https:\/\/www.hgg-group.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.hgg-group.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.hgg-group.com\/wp-content\/uploads\/2025\/03\/HGG_logo-primair_RGB.png","contentUrl":"https:\/\/www.hgg-group.com\/wp-content\/uploads\/2025\/03\/HGG_logo-primair_RGB.png","width":1097,"height":1337,"caption":"HGG"},"image":{"@id":"https:\/\/www.hgg-group.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.hgg-group.com\/de\/wp-json\/wp\/v2\/knowledge\/25592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hgg-group.com\/de\/wp-json\/wp\/v2\/knowledge"}],"about":[{"href":"https:\/\/www.hgg-group.com\/de\/wp-json\/wp\/v2\/types\/knowledge"}],"version-history":[{"count":0,"href":"https:\/\/www.hgg-group.com\/de\/wp-json\/wp\/v2\/knowledge\/25592\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hgg-group.com\/de\/wp-json\/wp\/v2\/media\/4936"}],"wp:attachment":[{"href":"https:\/\/www.hgg-group.com\/de\/wp-json\/wp\/v2\/media?parent=25592"}],"wp:term":[{"taxonomy":"knowledge-tag","embeddable":true,"href":"https:\/\/www.hgg-group.com\/de\/wp-json\/wp\/v2\/knowledge-tag?post=25592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}